{"id":830668,"date":"2025-01-17T07:36:17","date_gmt":"2025-01-17T07:36:17","guid":{"rendered":"https:\/\/www.bravilor.com\/products\/esprecious-21l\/"},"modified":"2026-07-13T20:16:36","modified_gmt":"2026-07-13T20:16:36","slug":"esprecious-21l","status":"publish","type":"product","link":"https:\/\/www.bravilor.com\/es\/products\/espresso-machines-es\/esprecious-21l\/","title":{"rendered":"Esprecious 21L"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","product_category":[1774,4969],"product_family":[1232],"recommended_usage":[3466,3505,3310,3349],"user_amount":[3583,3622,3661],"ingredient":[219,284,2996],"peak_consumption":[562],"water_connection":[2963],"choice_of_beverages":[996,1024,1050,1063,1089,1102,4399,4441,4519,4558,833,846,859,918,957,983],"milk_function":[2915],"configuration_comparison":[],"class_list":["post-830668","product","type-product","status-publish","hentry","product_category-espresso-machines-es","product_category-esprecious-es","product_family-espresso-machines-es","recommended_usage-up-to-30-es","recommended_usage-up-to-60-es","recommended_usage-up-to-100-es","recommended_usage-up-to-120-es","user_amount-10-20-users-es","user_amount-10-35-users-es","user_amount-20-40-users-es","ingredient-coffeebeans-es","ingredient-milk-es","ingredient-instant-ingredients-es","peak_consumption-no-es","water_connection-yes-es","choice_of_beverages-espressochoc-es","choice_of_beverages-hot-chocolate-es","choice_of_beverages-hot-water-es","choice_of_beverages-latte-macchiato-es","choice_of_beverages-moccachino-es","choice_of_beverages-ristretto-es","choice_of_beverages-flat-white-es","choice_of_beverages-hot-milk-es","choice_of_beverages-long-black-es","choice_of_beverages-lungo-es","choice_of_beverages-cafe-au-lait-es","choice_of_beverages-cappuccino-es","choice_of_beverages-cappuccino-dark-es","choice_of_beverages-crema-coffee-es","choice_of_beverages-espresso-es","choice_of_beverages-espresso-macchiato-es","milk_function-yes-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Esprecious 21L - Bravilor Bonamat<\/title>\n<meta name=\"description\" content=\"Descubre Esprecious 21L en Bravilor Bonamat! Obt\u00e9n m\u00e1s informaci\u00f3n sobre Esprecious 21L y cont\u00e1ctanos para asesoramiento profesional y opciones de compra.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bravilor.com\/es\/products\/espresso-machines-es\/esprecious-21l\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Esprecious 21L - Bravilor Bonamat\" \/>\n<meta property=\"og:description\" content=\"Descubre Esprecious 21L en Bravilor Bonamat! Obt\u00e9n m\u00e1s informaci\u00f3n sobre Esprecious 21L y cont\u00e1ctanos para asesoramiento profesional y opciones de compra.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bravilor.com\/es\/products\/espresso-machines-es\/esprecious-21l\/\" \/>\n<meta property=\"og:site_name\" content=\"Bravilor Bonamat\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bravilor.bonamat.bv\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-13T20:16:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bravilor.com\\\/es\\\/products\\\/espresso-machines-es\\\/esprecious-21l\\\/\",\"url\":\"https:\\\/\\\/www.bravilor.com\\\/es\\\/products\\\/espresso-machines-es\\\/esprecious-21l\\\/\",\"name\":\"Esprecious 21L - Bravilor Bonamat\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bravilor.com\\\/es\\\/#website\"},\"datePublished\":\"2025-01-17T07:36:17+00:00\",\"dateModified\":\"2026-07-13T20:16:36+00:00\",\"description\":\"Descubre Esprecious 21L en Bravilor Bonamat! Obt\u00e9n m\u00e1s informaci\u00f3n sobre Esprecious 21L y cont\u00e1ctanos para asesoramiento profesional y opciones de compra.\",\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bravilor.com\\\/es\\\/products\\\/espresso-machines-es\\\/esprecious-21l\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bravilor.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.bravilor.com\\\/es\\\/\",\"name\":\"Bravilor Bonamat\",\"description\":\"Professional coffee machines and hot water dispensers\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bravilor.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bravilor.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bravilor.com\\\/es\\\/#organization\",\"name\":\"Bravilor Bonamat\",\"url\":\"https:\\\/\\\/www.bravilor.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.bravilor.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bravilor.com\\\/app\\\/uploads\\\/2024\\\/01\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.bravilor.com\\\/app\\\/uploads\\\/2024\\\/01\\\/logo.svg\",\"width\":1,\"height\":1,\"caption\":\"Bravilor Bonamat\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bravilor.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bravilor.bonamat.bv\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Esprecious 21L - Bravilor Bonamat","description":"Descubre Esprecious 21L en Bravilor Bonamat! Obt\u00e9n m\u00e1s informaci\u00f3n sobre Esprecious 21L y cont\u00e1ctanos para asesoramiento profesional y opciones de compra.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bravilor.com\/es\/products\/espresso-machines-es\/esprecious-21l\/","og_locale":"es_ES","og_type":"article","og_title":"Esprecious 21L - Bravilor Bonamat","og_description":"Descubre Esprecious 21L en Bravilor Bonamat! Obt\u00e9n m\u00e1s informaci\u00f3n sobre Esprecious 21L y cont\u00e1ctanos para asesoramiento profesional y opciones de compra.","og_url":"https:\/\/www.bravilor.com\/es\/products\/espresso-machines-es\/esprecious-21l\/","og_site_name":"Bravilor Bonamat","article_publisher":"https:\/\/www.facebook.com\/bravilor.bonamat.bv","article_modified_time":"2026-07-13T20:16:36+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bravilor.com\/es\/products\/espresso-machines-es\/esprecious-21l\/","url":"https:\/\/www.bravilor.com\/es\/products\/espresso-machines-es\/esprecious-21l\/","name":"Esprecious 21L - Bravilor Bonamat","isPartOf":{"@id":"https:\/\/www.bravilor.com\/es\/#website"},"datePublished":"2025-01-17T07:36:17+00:00","dateModified":"2026-07-13T20:16:36+00:00","description":"Descubre Esprecious 21L en Bravilor Bonamat! Obt\u00e9n m\u00e1s informaci\u00f3n sobre Esprecious 21L y cont\u00e1ctanos para asesoramiento profesional y opciones de compra.","inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bravilor.com\/es\/products\/espresso-machines-es\/esprecious-21l\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.bravilor.com\/es\/#website","url":"https:\/\/www.bravilor.com\/es\/","name":"Bravilor Bonamat","description":"Professional coffee machines and hot water dispensers","publisher":{"@id":"https:\/\/www.bravilor.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bravilor.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.bravilor.com\/es\/#organization","name":"Bravilor Bonamat","url":"https:\/\/www.bravilor.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.bravilor.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.bravilor.com\/app\/uploads\/2024\/01\/logo.svg","contentUrl":"https:\/\/www.bravilor.com\/app\/uploads\/2024\/01\/logo.svg","width":1,"height":1,"caption":"Bravilor Bonamat"},"image":{"@id":"https:\/\/www.bravilor.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bravilor.bonamat.bv"]}]}},"_links":{"self":[{"href":"https:\/\/www.bravilor.com\/es\/wp-json\/wp\/v2\/product\/830668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bravilor.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.bravilor.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/www.bravilor.com\/es\/wp-json\/wp\/v2\/media?parent=830668"}],"wp:term":[{"taxonomy":"product_category","embeddable":true,"href":"https:\/\/www.bravilor.com\/es\/wp-json\/wp\/v2\/product_category?post=830668"},{"taxonomy":"product_family","embeddable":true,"href":"https:\/\/www.bravilor.com\/es\/wp-json\/wp\/v2\/product_family?post=830668"},{"taxonomy":"recommended_usage","embeddable":true,"href":"https:\/\/www.bravilor.com\/es\/wp-json\/wp\/v2\/recommended_usage?post=830668"},{"taxonomy":"user_amount","embeddable":true,"href":"https:\/\/www.bravilor.com\/es\/wp-json\/wp\/v2\/user_amount?post=830668"},{"taxonomy":"ingredient","embeddable":true,"href":"https:\/\/www.bravilor.com\/es\/wp-json\/wp\/v2\/ingredient?post=830668"},{"taxonomy":"peak_consumption","embeddable":true,"href":"https:\/\/www.bravilor.com\/es\/wp-json\/wp\/v2\/peak_consumption?post=830668"},{"taxonomy":"water_connection","embeddable":true,"href":"https:\/\/www.bravilor.com\/es\/wp-json\/wp\/v2\/water_connection?post=830668"},{"taxonomy":"choice_of_beverages","embeddable":true,"href":"https:\/\/www.bravilor.com\/es\/wp-json\/wp\/v2\/choice_of_beverages?post=830668"},{"taxonomy":"milk_function","embeddable":true,"href":"https:\/\/www.bravilor.com\/es\/wp-json\/wp\/v2\/milk_function?post=830668"},{"taxonomy":"configuration_comparison","embeddable":true,"href":"https:\/\/www.bravilor.com\/es\/wp-json\/wp\/v2\/configuration_comparison?post=830668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}